{"id":4539,"date":"2025-12-12T18:32:58","date_gmt":"2025-12-12T17:32:58","guid":{"rendered":"https:\/\/pre.juanacrespo.com\/?post_type=especialista&#038;p=4539"},"modified":"2026-05-14T11:38:36","modified_gmt":"2026-05-14T09:38:36","slug":"dra-darya-dudenko","status":"publish","type":"especialista","link":"https:\/\/juanacrespo.com\/it\/specialista\/dra-darya-dudenko\/","title":{"rendered":"Dra. Darya Dudenko"},"content":{"rendered":"<p>Doctora con Summa Cum Laude por la Universidad de Valencia, Licenciada en Medicina y Cirug\u00eda por la Universidad Rovira y Virgili, especializada en Ginecolog\u00eda y Obstetricia en el Hospital Cl\u00ednico de Valencia.<\/p>\n<p>Cuenta con el M\u00e1ster en Reproducci\u00f3n Asistida Humana La Dra. Dudenko ha trabajado como ginec\u00f3loga especialista en fertilidad en importantes cl\u00ednicas y hospitales privados en Londres.<\/p>\n<p>Son numerosas sus publicaciones cient\u00edficas, as\u00ed como sus trabajos de investigaci\u00f3n y papers presentados en los congresos de las principales sociedades cient\u00edficas.<\/p>\n<p>En la actualidad la Dra. Darya Dudenko es especialista en fertilidad en el \u00e1rea internacional de Equipo Juana Crespo ofreciendo a sus pacientes la posibilidad de consultas en ruso, ucraniano e ingl\u00e9s, idiomas en los que la doctora es nativa.<\/p>\n","protected":false},"featured_media":5777,"template":"","meta":{"_acf_changed":false,"content-type":"","inline_featured_image":false},"clinica":[],"ubicacion":[15,16],"unidad":[17],"class_list":["post-4539","especialista","type-especialista","status-publish","has-post-thumbnail","hentry","ubicacion-valencia","ubicacion-peniscola","unidad-medicina-reproductiva"],"acf":[],"_links":{"self":[{"href":"https:\/\/juanacrespo.com\/it\/wp-json\/wp\/v2\/especialista\/4539","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/juanacrespo.com\/it\/wp-json\/wp\/v2\/especialista"}],"about":[{"href":"https:\/\/juanacrespo.com\/it\/wp-json\/wp\/v2\/types\/especialista"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/juanacrespo.com\/it\/wp-json\/wp\/v2\/media\/5777"}],"wp:attachment":[{"href":"https:\/\/juanacrespo.com\/it\/wp-json\/wp\/v2\/media?parent=4539"}],"wp:term":[{"taxonomy":"clinica","embeddable":true,"href":"https:\/\/juanacrespo.com\/it\/wp-json\/wp\/v2\/clinica?post=4539"},{"taxonomy":"ubicacion","embeddable":true,"href":"https:\/\/juanacrespo.com\/it\/wp-json\/wp\/v2\/ubicacion?post=4539"},{"taxonomy":"unidad","embeddable":true,"href":"https:\/\/juanacrespo.com\/it\/wp-json\/wp\/v2\/unidad?post=4539"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}